{"id":5672527,"date":"2024-07-14T19:43:56","date_gmt":"2024-07-14T19:43:56","guid":{"rendered":"https:\/\/cpg.ihub4.dev\/?page_id=5672527"},"modified":"2026-04-02T19:27:36","modified_gmt":"2026-04-02T19:27:36","slug":"oratorio","status":"publish","type":"page","link":"https:\/\/www.centropapagiovanni.ch\/index.php\/i-nostri-gruppi\/oratorio\/","title":{"rendered":"OrAtOrIo-Teens"},"content":{"rendered":"<section class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_empty_space]<div class=\"norebro-heading-sc heading text-left\"\n\tid=\"norebro-custom-6a046dbed11fc\" \n\t \n\t>\n\t\n\t\t\t<p class=\"subtitle\">\n\t\t\t\t\t<\/p>\n\t\n\t\n\t<h1 class=\"title subtitle-top\">\n\t\tOrAtOrIo-Teens\t<\/h1>\n\n\t\n\t\t\n<\/div>[vc_empty_space]<div class=\"norebro-text-sc \" \n\tid=\"norebro-custom-6a046dbed134f\" \n\t \n\t>\n\n\t<p>Da alcuni anni nella nostra Missione abbiamo l&#8217;onore di poter fare un cammino insieme a diverse famiglie.<\/p>\n<p>L&#8217;OrAtOrIo \u00e8 cos\u00ec vivo, grazie proprio al contributo di tante mamme volenterose. Con loro si fa tutta la programmazione e si decidono le diverse attivit\u00e0.<\/p>\n<p>Ci incontriamo <strong>tutti i mercoled\u00ec per mamme e bambini<\/strong> <strong>da 0-11 anni dalle ore 14.00-17.00<\/strong> circa presso il Centro Papa Giovanni.<\/p>\n<p>Invece per ragazzi <strong>\u201cTeens\u201d dai 12-16 anni ci incontriamo tutti i venerd\u00ec dalle ore 20.00-22.00<\/strong> circa presso il Centro Papa Giovanni.<\/p>\n<p>Per qualsiasi informazione potete prendere contatto con <a href=\"\/index.php\/contatti\/\"><strong>Maria Carminitana<\/strong><\/a> scrivendo una mail.<\/p>\n\t\n<\/div>[\/vc_column][\/vc_row]\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":5672477,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5672527","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.centropapagiovanni.ch\/index.php\/wp-json\/wp\/v2\/pages\/5672527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centropapagiovanni.ch\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.centropapagiovanni.ch\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.centropapagiovanni.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.centropapagiovanni.ch\/index.php\/wp-json\/wp\/v2\/comments?post=5672527"}],"version-history":[{"count":7,"href":"https:\/\/www.centropapagiovanni.ch\/index.php\/wp-json\/wp\/v2\/pages\/5672527\/revisions"}],"predecessor-version":[{"id":5674645,"href":"https:\/\/www.centropapagiovanni.ch\/index.php\/wp-json\/wp\/v2\/pages\/5672527\/revisions\/5674645"}],"up":[{"embeddable":true,"href":"https:\/\/www.centropapagiovanni.ch\/index.php\/wp-json\/wp\/v2\/pages\/5672477"}],"wp:attachment":[{"href":"https:\/\/www.centropapagiovanni.ch\/index.php\/wp-json\/wp\/v2\/media?parent=5672527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}